{"id":2395,"date":"2024-02-05T19:43:31","date_gmt":"2024-02-05T18:43:31","guid":{"rendered":"https:\/\/marcopontes.es\/servicios-copy\/"},"modified":"2026-04-28T09:57:38","modified_gmt":"2026-04-28T07:57:38","slug":"lab","status":"publish","type":"page","link":"https:\/\/marcopontes.es\/en\/lab\/","title":{"rendered":"LAB"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2395\" class=\"elementor elementor-2395\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67a1bf3 e-flex e-con-boxed e-con e-parent\" data-id=\"67a1bf3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-e-bg-lazyload=\"\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-37938de e-flex e-con-boxed e-con e-child\" data-id=\"37938de\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a42351e elementor-widget elementor-widget-heading\" data-id=\"a42351e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 20-12-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h3 class=\"elementor-heading-title elementor-size-default\">LABORATORIO<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f6cc65 e-flex e-con-boxed e-con e-parent\" data-id=\"4f6cc65\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e2b905 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-posts--show-avatar elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"8e2b905\" data-element_type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/marcopontes.es\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-posts.min.css\">\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4164 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/identidad-grafica-premios-jose-marsal-caballero\/\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2025\/01\/Portada-gala-premios-43-jmc-1024x678.webp\" class=\"attachment-large size-large wp-image-4167\" alt=\"gala d\u00e9nia fm\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2025\/01\/Portada-gala-premios-43-jmc-1024x678.webp 1024w, https:\/\/marcopontes.es\/wp-content\/uploads\/2025\/01\/Portada-gala-premios-43-jmc-300x199.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2025\/01\/Portada-gala-premios-43-jmc-768x509.webp 768w, https:\/\/marcopontes.es\/wp-content\/uploads\/2025\/01\/Portada-gala-premios-43-jmc-1536x1018.webp 1536w, https:\/\/marcopontes.es\/wp-content\/uploads\/2025\/01\/Portada-gala-premios-43-jmc-2048x1357.webp 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/identidad-grafica-premios-jose-marsal-caballero\/\" >\n\t\t\t\tIDENTIDAD GR\u00c1FICA | XLIII Premios Jos\u00e9 Marsal Caballero\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>IDENTIDAD GR\u00c1FICA XLIII Premios Jos\u00e9 Marsal Caballero \/\/ Contexto del evento El jueves 21 de noviembre de 2024, Denia, Alicante, acogi\u00f3 los 43\u00ba Premios Jos\u00e9 Marsal Caballero, organizados por Denia<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/identidad-grafica-premios-jose-marsal-caballero\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t12 de January de 2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4094 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/masorange\/\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/04\/logoO_negativo-1024x678.webp\" class=\"attachment-large size-large wp-image-4097\" alt=\"logo de masorange\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/04\/logoO_negativo-1024x678.webp 1024w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/04\/logoO_negativo-300x199.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/04\/logoO_negativo-768x509.webp 768w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/04\/logoO_negativo-1536x1017.webp 1536w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/04\/logoO_negativo-2048x1356.webp 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/masorange\/\" >\n\t\t\t\tMASORANGE | Fusi\u00f3n de Identidades Corporativas\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>MASORANGE Fusi\u00f3n de Identidades Corporativas M\u00e1sM\u00f3vil y Orange unen sus fuerzas para liderar el mercado de telecomunicaciones. Nace su nueva identidad corporativa: MASORANGE. La Nueva Identidad Corporativa La nueva identidad<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/masorange\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t10 de April de 2024\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4079 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/decathlon-rebranding\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/04\/Decathlon-Cover-1024x576.webp\" class=\"attachment-large size-large wp-image-4082\" alt=\"rebranding de decathlon\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/04\/Decathlon-Cover-1024x576.webp 1024w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/04\/Decathlon-Cover-300x169.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/04\/Decathlon-Cover-768x432.webp 768w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/04\/Decathlon-Cover-1536x864.webp 1536w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/04\/Decathlon-Cover.webp 1921w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/decathlon-rebranding\/\" >\n\t\t\t\tDecathlon | Rebranding\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>DECATHLONRebranding con nuevo isotipo La nueva imagen refleja una est\u00e9tica moderna y vibrante, acorde con los tiempos actuales y las tendencias del mercado. Adem\u00e1s implementan cambios en estructura de marca<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/decathlon-rebranding\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t5 de April de 2024\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3265 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/diseno-sensorial\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"714\" height=\"400\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/diseno-sensorial.webp\" class=\"attachment-large size-large wp-image-3267\" alt=\"portada art\u00edculo dise\u00f1o sensorial\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/diseno-sensorial.webp 714w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/diseno-sensorial-300x168.webp 300w\" sizes=\"(max-width: 714px) 100vw, 714px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/diseno-sensorial\/\" >\n\t\t\t\tDise\u00f1o Sensorial\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>EL DISE\u00d1O SENSORIALa trav\u00e9s de los sentidos Proyecto &#8211; Exposici\u00f3n sobre la relaci\u00f3n entre los sentidos y el dise\u00f1o. \u201cTodos somos instrumentos dotados de sentimiento y memoria. Nuestros sentidos son<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/diseno-sensorial\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t14 de February de 2024\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3251 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/mobile-first-la-innovacion-tecnologica-en-marcas\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"448\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/mobile-first-1024x573.webp\" class=\"attachment-large size-large wp-image-3254\" alt=\"mobile first app\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/mobile-first-1024x573.webp 1024w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/mobile-first-300x168.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/mobile-first-768x430.webp 768w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/mobile-first.webp 1457w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/mobile-first-la-innovacion-tecnologica-en-marcas\/\" >\n\t\t\t\tMobile First | La innovaci\u00f3n tecnol\u00f3gica en marcas\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>MOBILE FIRST La innovaci\u00f3n tecnol\u00f3gica en marcas CRUZCAMPO &#8211; MOBILE FIRST An\u00e1lisis de la comunicaci\u00f3n de la marca, User Journey y propuesta de APP \u00a0 Antes de nada, para una<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/mobile-first-la-innovacion-tecnologica-en-marcas\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t6 de February de 2024\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3203 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/entorno-de-marca\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Entorno-de-marca.webp\" class=\"attachment-large size-large wp-image-2507\" alt=\"cover del art\u00edculo Entorno de marca\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Entorno-de-marca.webp 821w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Entorno-de-marca-300x200.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Entorno-de-marca-768x512.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/entorno-de-marca\/\" >\n\t\t\t\tEntorno de Marca de un Parque Industrial en Cambridge, UK\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Entorno de Marca de un Parque Industrial en Cambridge, UK T\u00edtulo: Naves Parque Industrial Autor: Marco Pontes A\u00f1o: 2021 Contexto Analizar\u00e9 el entorno de marca de un peque\u00f1o parque industrial<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/entorno-de-marca\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t6 de November de 2023\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3193 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/proyecto-de-identidad-verbal\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Proyecto-identidad-verbal.webp\" class=\"attachment-large size-large wp-image-2510\" alt=\"cover para el art\u00edculo Proyecto identidad verbal\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Proyecto-identidad-verbal.webp 874w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Proyecto-identidad-verbal-300x169.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Proyecto-identidad-verbal-768x432.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/proyecto-de-identidad-verbal\/\" >\n\t\t\t\tProyecto de Identidad Verbal\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Proyecto de Identidad Verbal \u00abLas marcas son personas que hablan con otras personas, conviven e interact\u00faan con ellas de manera rec\u00edproca\u00bb. Las marcas no se constituyen solo por una identidad<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/proyecto-de-identidad-verbal\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t2 de October de 2023\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3221 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/marcas-identidades-y-contracultura\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Marcas-Identidades-y-Contracultura.webp\" class=\"attachment-large size-large wp-image-2509\" alt=\"cover del art\u00edculo Marcas, Identidades y Contracultura\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Marcas-Identidades-y-Contracultura.webp 820w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Marcas-Identidades-y-Contracultura-300x200.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Marcas-Identidades-y-Contracultura-768x512.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/marcas-identidades-y-contracultura\/\" >\n\t\t\t\tMarcas, Identidades y Contracultura\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Marcas,Identidades y Contracultura OBJETIVO DE ESTE ART\u00cdCULO En este art\u00edculo realizar\u00e9 un an\u00e1lisis de marcas e identidades que han tenido un impacto en mi vida, desde el enfoque te\u00f3rico de<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/marcas-identidades-y-contracultura\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t28 de September de 2023\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3116 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/historia-de-las-marcas-under-armour\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-underarmour.webp\" class=\"attachment-large size-large wp-image-2548\" alt=\"cover para el art\u00edculo de under armour\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-underarmour.webp 821w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-underarmour-300x200.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-underarmour-768x513.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/historia-de-las-marcas-under-armour\/\" >\n\t\t\t\tHistoria de la marcas: Under Armour (5\/5)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Historia de la marcas: Under Armour(5\/5) CONTENIDO &#8211; UNDER ARMOUR Viajaremos a lo largo de la historia de las cinco marcas objeto de an\u00e1lisis desde sus inicios hasta la actualidad.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/historia-de-las-marcas-under-armour\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t16 de August de 2023\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3107 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/historia-de-las-marcas-kelme\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"535\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-kelme.webp\" class=\"attachment-large size-large wp-image-2545\" alt=\"cover para el art\u00edculo de kelme\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-kelme.webp 820w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-kelme-300x200.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-kelme-768x513.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/historia-de-las-marcas-kelme\/\" >\n\t\t\t\tHistoria de la marcas: Kelme (4\/5)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Historia de la marcas: Kelme (4\/5) CONTENIDO &#8211; KELME Kelme. Viajaremos a lo largo de la historia de las cinco marcas objeto de an\u00e1lisis desde sus inicios hasta la actualidad.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/historia-de-las-marcas-kelme\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t9 de August de 2023\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3098 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/historia-de-las-marcas-nike\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-nike.webp\" class=\"attachment-large size-large wp-image-2546\" alt=\"cover para el art\u00edculo de nike\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-nike.webp 820w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-nike-300x200.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-nike-768x512.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/historia-de-las-marcas-nike\/\" >\n\t\t\t\tHistoria de la marcas: Nike (3\/5)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Historia de la marcas: Nike (3\/5) CONTENIDO &#8211; NIKE Viajaremos a lo largo de la historia de las cinco marcas objeto de an\u00e1lisis desde sus inicios hasta la actualidad. Desde<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/historia-de-las-marcas-nike\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t1 de August de 2023\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3093 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/historia-de-las-marcas-adidas\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-adidas.webp\" class=\"attachment-large size-large wp-image-2544\" alt=\"cover para el art\u00edculo de adidas\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-adidas.webp 820w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-adidas-300x200.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-adidas-768x512.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/historia-de-las-marcas-adidas\/\" >\n\t\t\t\tHistoria de la marcas: Adidas (2\/5)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Historia de la marcas: Adidas (2\/5) CONTENIDO &#8211; ADIDAS Viajaremos a lo largo de la historia de las cinco marcas objeto de an\u00e1lisis desde sus inicios hasta la actualidad. Desde<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/historia-de-las-marcas-adidas\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t25 de July de 2023\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3084 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/historia-de-las-marcas-reebok\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-reebok.webp\" class=\"attachment-large size-large wp-image-2547\" alt=\"cover para el art\u00edculo de reebok\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-reebok.webp 820w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-reebok-300x200.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/historia-reebok-768x512.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/historia-de-las-marcas-reebok\/\" >\n\t\t\t\tHistoria de la marcas: Reebok (1\/5)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Historia de la marcas: Reebok (1\/5) INTRODUCCI\u00d3N La identidad corporativa hoy d\u00eda es cada vez m\u00e1s aclamada. El mundo de la publicidad y el marketing nunca podr\u00e1 ser algo est\u00e1tico,<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/historia-de-las-marcas-reebok\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t14 de July de 2023\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3072 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/desigual-de-rebelde-a-cuidador\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/desigual.webp\" class=\"attachment-large size-large wp-image-2549\" alt=\"cover para el art\u00edculo de under armour\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/desigual.webp 821w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/desigual-300x200.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/desigual-768x512.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/desigual-de-rebelde-a-cuidador\/\" >\n\t\t\t\tDesigual, de rebelde a cuidador\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Desigual, de rebelde a cuidador CONTEXTO &#8211; DESIGUAL En esta ocasi\u00f3n hago un ejercicio de cambio radical de arquetipo para la marca Desigual, la cual se expresa con un arquetipo<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/desigual-de-rebelde-a-cuidador\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t6 de June de 2023\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3233 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/dove-en-profundidad\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Dove-en-profundidad-1024x682.webp\" class=\"attachment-large size-large wp-image-2506\" alt=\"Pila de libros antiguos con el texto &quot;En Profundidad&quot; y el logotipo de Dove sobre fondo negro.\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Dove-en-profundidad-1024x682.webp 1024w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Dove-en-profundidad-300x200.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Dove-en-profundidad-768x511.webp 768w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Dove-en-profundidad-1536x1023.webp 1536w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/Dove-en-profundidad.webp 1643w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/dove-en-profundidad\/\" >\n\t\t\t\tDOVE en profundidad\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>DOVE en profundidad An\u00e1lisis de marca &#8211; DOVE Productos de cuidado personal Dove. Una multinacional l\u00edder en su sector con m\u00e1s de 65 a\u00f1os de historia. Objetivo de este art\u00edculo:<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/dove-en-profundidad\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t15 de May de 2023\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2148 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/zero-waste-path-creating-a-sustainable-culture\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/zero-waste-path.webp\" class=\"attachment-large size-large wp-image-3024\" alt=\"\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/zero-waste-path.webp 820w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/zero-waste-path-300x200.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2024\/02\/zero-waste-path-768x512.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/zero-waste-path-creating-a-sustainable-culture\/\" >\n\t\t\t\tZero Waste Path\u2122: Creating a Sustainable Culture\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Zero Waste Path\u2122: Creating a Sustainable Culture Zero Waste Path is a small company dedicated to producing sustainable personal care products, located in Cambridge, England. The beginning Bianca Mularoni and<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/zero-waste-path-creating-a-sustainable-culture\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t9 de February de 2022\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3179 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/marcopontes.es\/en\/the-impact-of-brands-in-the-home-during-the-lockdown\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"437\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Brand-Impact-1-1024x559.webp\" class=\"attachment-large size-large wp-image-5346\" alt=\"Toma fotogr\u00e1fica atmosf\u00e9rica de un interior de hogar acogedor durante el aislamiento, con una persona relajada en un sill\u00f3n de dise\u00f1o Ikea, un altavoz Alexa brillando y un iRobot Roomba en el suelo, con el mundo exterior borroso.\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Brand-Impact-1-1024x559.webp 1024w, https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Brand-Impact-1-300x164.webp 300w, https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Brand-Impact-1-768x419.webp 768w, https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Brand-Impact-1-18x10.webp 18w, https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Brand-Impact-1.webp 1408w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Blog<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2-150x150.png\" width=\"128\" height=\"128\" srcset=\"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/Marco-Pontes-2.png 2x\" alt=\"Marco Pontes\" class=\"avatar avatar-128 wp-user-avatar wp-user-avatar-128 alignnone photo\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/marcopontes.es\/en\/the-impact-of-brands-in-the-home-during-the-lockdown\/\" >\n\t\t\t\tThe impact of brands in the home during the lockdown\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Brand impact at home during lockdown The impact of the brands \u00a0 Nowadays what is ruling the market is the adjustment to the new digital age and the required time<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/marcopontes.es\/en\/the-impact-of-brands-in-the-home-during-the-lockdown\/\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t18 de June de 2021\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNo Comments\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\n\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f24d48 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8f24d48\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 20-12-2023 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>LABORATORY<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2395","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LAB<\/title>\n<meta name=\"description\" content=\"Art\u00edculos sobre Branding, estrategia de marca, casos pr\u00e1cticos, an\u00e1lisis y muchos m\u00e1s! Entra y emp\u00e1pate de las curiosidades del branding!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcopontes.es\/en\/lab\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LAB\" \/>\n<meta property=\"og:description\" content=\"Art\u00edculos sobre Branding, estrategia de marca, casos pr\u00e1cticos, an\u00e1lisis y muchos m\u00e1s! Entra y emp\u00e1pate de las curiosidades del branding!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcopontes.es\/en\/lab\/\" \/>\n<meta property=\"og:site_name\" content=\"Branding y Dise\u00f1o Gr\u00e1fico\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T07:57:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcopontes.es\\\/lab\\\/\",\"url\":\"https:\\\/\\\/marcopontes.es\\\/lab\\\/\",\"name\":\"LAB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcopontes.es\\\/#website\"},\"datePublished\":\"2024-02-05T18:43:31+00:00\",\"dateModified\":\"2026-04-28T07:57:38+00:00\",\"description\":\"Art\u00edculos sobre Branding, estrategia de marca, casos pr\u00e1cticos, an\u00e1lisis y muchos m\u00e1s! Entra y emp\u00e1pate de las curiosidades del branding!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcopontes.es\\\/lab\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcopontes.es\\\/lab\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcopontes.es\\\/lab\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/marcopontes.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LAB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcopontes.es\\\/#website\",\"url\":\"https:\\\/\\\/marcopontes.es\\\/\",\"name\":\"Branding y Dise\u00f1o Gr\u00e1fico\",\"description\":\"Branding\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcopontes.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcopontes.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcopontes.es\\\/#organization\",\"name\":\"Branding y Dise\u00f1o Gr\u00e1fico\",\"url\":\"https:\\\/\\\/marcopontes.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/marcopontes.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marcopontes.es\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/MarcoPontes-Logo-Navy-1.png\",\"contentUrl\":\"https:\\\/\\\/marcopontes.es\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/MarcoPontes-Logo-Navy-1.png\",\"width\":373,\"height\":216,\"caption\":\"Branding y Dise\u00f1o Gr\u00e1fico\"},\"image\":{\"@id\":\"https:\\\/\\\/marcopontes.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LAB","description":"Art\u00edculos sobre Branding, estrategia de marca, casos pr\u00e1cticos, an\u00e1lisis y muchos m\u00e1s! Entra y emp\u00e1pate de las curiosidades del branding!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcopontes.es\/en\/lab\/","og_locale":"en_GB","og_type":"article","og_title":"LAB","og_description":"Art\u00edculos sobre Branding, estrategia de marca, casos pr\u00e1cticos, an\u00e1lisis y muchos m\u00e1s! Entra y emp\u00e1pate de las curiosidades del branding!","og_url":"https:\/\/marcopontes.es\/en\/lab\/","og_site_name":"Branding y Dise\u00f1o Gr\u00e1fico","article_modified_time":"2026-04-28T07:57:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/marcopontes.es\/lab\/","url":"https:\/\/marcopontes.es\/lab\/","name":"LAB","isPartOf":{"@id":"https:\/\/marcopontes.es\/#website"},"datePublished":"2024-02-05T18:43:31+00:00","dateModified":"2026-04-28T07:57:38+00:00","description":"Art\u00edculos sobre Branding, estrategia de marca, casos pr\u00e1cticos, an\u00e1lisis y muchos m\u00e1s! Entra y emp\u00e1pate de las curiosidades del branding!","breadcrumb":{"@id":"https:\/\/marcopontes.es\/lab\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcopontes.es\/lab\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/marcopontes.es\/lab\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/marcopontes.es\/es\/"},{"@type":"ListItem","position":2,"name":"LAB"}]},{"@type":"WebSite","@id":"https:\/\/marcopontes.es\/#website","url":"https:\/\/marcopontes.es\/","name":"Branding y Dise\u00f1o Gr\u00e1fico","description":"Branding","publisher":{"@id":"https:\/\/marcopontes.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcopontes.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/marcopontes.es\/#organization","name":"Branding y Dise\u00f1o Gr\u00e1fico","url":"https:\/\/marcopontes.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/marcopontes.es\/#\/schema\/logo\/image\/","url":"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/MarcoPontes-Logo-Navy-1.png","contentUrl":"https:\/\/marcopontes.es\/wp-content\/uploads\/2026\/04\/MarcoPontes-Logo-Navy-1.png","width":373,"height":216,"caption":"Branding y Dise\u00f1o Gr\u00e1fico"},"image":{"@id":"https:\/\/marcopontes.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/marcopontes.es\/en\/wp-json\/wp\/v2\/pages\/2395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcopontes.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/marcopontes.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/marcopontes.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marcopontes.es\/en\/wp-json\/wp\/v2\/comments?post=2395"}],"version-history":[{"count":29,"href":"https:\/\/marcopontes.es\/en\/wp-json\/wp\/v2\/pages\/2395\/revisions"}],"predecessor-version":[{"id":5667,"href":"https:\/\/marcopontes.es\/en\/wp-json\/wp\/v2\/pages\/2395\/revisions\/5667"}],"wp:attachment":[{"href":"https:\/\/marcopontes.es\/en\/wp-json\/wp\/v2\/media?parent=2395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}